{"id":2817,"date":"2016-03-29T00:51:55","date_gmt":"2016-03-29T06:51:55","guid":{"rendered":"http:\/\/cristinacortinas.org\/sustentabilidad\/?page_id=2817"},"modified":"2017-06-21T15:05:38","modified_gmt":"2017-06-21T20:05:38","slug":"programa-de-residuos-jalisco","status":"publish","type":"page","link":"https:\/\/cristinacortinas.org\/sustentabilidad\/programa-de-residuos-jalisco\/","title":{"rendered":"Programas y normas de residuos en Jalisco"},"content":{"rendered":"<div class=\"span12 \"><div class=\"title-box clearfix \"><h2 class=\"title-box_primary\">descargas<\/h2><\/div><!-- \/\/.title-box --><\/div>\n<hr \/>\n<div class=\"span7 \"><div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/estatal-para-la-prevencion-y-gestion-integral-de-los-residuos-del-estado-de-jalisco-2016-2022\/'>Programa Estatal para la Prevenci\u00f3n y Gesti\u00f3n Integral de los Residuos del Estado de Jalisco 2016-2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 9.55 MB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/estatal-para-la-prevencion-y-gestion-integral-de-los-residuos-del-estado-de-jalisco-2016-2022\/?wpdmdl=4349&refresh=6a97eddc104bf1788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/docx.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/programa-estatal-de-residuos-periodico-oficial-2017\/'>Programa Estatal de Residuos Peri\u00f3dico Oficial 2017 (245Mb)<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 40.00 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/programa-estatal-de-residuos-periodico-oficial-2017\/?wpdmdl=4299&refresh=6a97eddc161a71788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/reglamento-para-la-prevencion-y-gestion-integral-de-residuos-solidos-para-el-municipio-de-mazamitla\/'>Reglamento para la Prevenci\u00f3n y Gesti\u00f3n Integral de Residuos S\u00f3lidos para el Municipio de Mazamitla<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 136.48 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/reglamento-para-la-prevencion-y-gestion-integral-de-residuos-solidos-para-el-municipio-de-mazamitla\/?wpdmdl=3110&refresh=6a97eddc1cf021788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/reglamento-de-residuos-de-zapopan-jalisco\/'>Reglamento de Residuos de Zapopan Jalisco<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 279.94 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/reglamento-de-residuos-de-zapopan-jalisco\/?wpdmdl=3082&refresh=6a97eddc238991788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/reglamento-de-residuos-de-etzatlan-jalisco\/'>Reglamento de Residuos de Etzatl\u00e1n Jalisco<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 187.42 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/reglamento-de-residuos-de-etzatlan-jalisco\/?wpdmdl=3078&refresh=6a97eddc2b5eb1788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/reglamento-de-residuos-yahualica-de-gonzalez-gallo-jalisco\/'>Reglamento de Residuos Yahualica de Gonz\u00e1lez Gallo  Jalisco<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 271.24 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/reglamento-de-residuos-yahualica-de-gonzalez-gallo-jalisco\/?wpdmdl=3086&refresh=6a97eddc311231788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/reglamento-aseo-publico-jamay-jalisco\/'>Reglamento aseo p\u00fablico Jamay Jalisco<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 308.57 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/reglamento-aseo-publico-jamay-jalisco\/?wpdmdl=3088&refresh=6a97eddc391001788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/docx.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/reglamento-de-residuos-zapotiltil-jalisco\/'>Reglamento de Residuos Zapotiltil Jalisco<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 110.00 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/reglamento-de-residuos-zapotiltil-jalisco\/?wpdmdl=3090&refresh=6a97eddc3f5c41788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/norma-ambiental-estatal-007-para-la-separacion-recoleccion-selectiva-y-valorizacion-de-residuos\/'>Norma Ambiental Estatal 007 para la Separaci\u00f3n, Recolecci\u00f3n Selectiva y Valorizaci\u00f3n de Residuos<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 307.25 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/norma-ambiental-estatal-007-para-la-separacion-recoleccion-selectiva-y-valorizacion-de-residuos\/?wpdmdl=2841&refresh=6a97eddc43b981788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/docx.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/ley-para-la-accion-ante-el-cambio-climatico-del-estado-de-jalisco\/'>Ley para la Acci\u00f3n ante el Cambio Clim\u00e1tico del Estado de Jalisco<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 242.00 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/ley-para-la-accion-ante-el-cambio-climatico-del-estado-de-jalisco\/?wpdmdl=2839&refresh=6a97eddc483961788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/reglamento-de-la-ley-estatal-del-equilibrio-ecologico-y-la-proteccion-al-ambiente-en-materia-del-impacto-ambiental\/'>Reglamento de la Ley Estatal del Equilibrio Ecol\u00f3gico y  la Protecci\u00f3n al Ambiente en Materia del Impacto Ambiental<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 73.86 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/reglamento-de-la-ley-estatal-del-equilibrio-ecologico-y-la-proteccion-al-ambiente-en-materia-del-impacto-ambiental\/?wpdmdl=3303&refresh=6a97eddc4cc751788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/ley-estatal-del-equilibrio-ecologico-y-la-proteccion-al-ambiente-del-estado-de-jalisco\/'>Ley Estatal del Equilibrio Ecol\u00f3gico y la Protecci\u00f3n al Ambiente del Estado de Jalisco<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 133.07 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/ley-estatal-del-equilibrio-ecologico-y-la-proteccion-al-ambiente-del-estado-de-jalisco\/?wpdmdl=2837&refresh=6a97eddc515ed1788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/ley-de-gestion-integral-de-residuos-del-estado-de-jalisco\/'>Ley de Gesti\u00f3n Integral de Residuos del Estado de Jalisco<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 189.38 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/ley-de-gestion-integral-de-residuos-del-estado-de-jalisco\/?wpdmdl=2835&refresh=6a97eddc5671a1788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/programa-estatal-para-la-prevencion-y-gestion-integral-de-residuos-del-estado-de-jalisco-2010-2017\/'>Programa Estatal para la Prevenci\u00f3n y Gesti\u00f3n Integral de Residuos del Estado de Jalisco 2010 \u2013 2017<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 7.57 MB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/programa-estatal-para-la-prevencion-y-gestion-integral-de-residuos-del-estado-de-jalisco-2010-2017\/?wpdmdl=2846&refresh=6a97eddc5ae191788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/programa-intermunicipal-para-la-prevencion-y-gestion-integral-de-residuos-solidos-lagunas-2015-2020\/'>Programa Intermunicipal para la Prevenci\u00f3n y Gesti\u00f3n Integral de Residuos S\u00f3lidos Lagunas 2015-2020<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 13.02 MB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/programa-intermunicipal-para-la-prevencion-y-gestion-integral-de-residuos-solidos-lagunas-2015-2020\/?wpdmdl=2848&refresh=6a97eddc5f6f71788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/programa-intermunicipal-para-la-prevencion-y-gestion-integral-de-residuos-solidos-de-los-municipios-de-la-jisoc\/'>Programa Intermunicipal para la Prevenci\u00f3n y Gesti\u00f3n Integral de Residuos S\u00f3lidos de los Municipios de la JISOC<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 25.40 MB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/programa-intermunicipal-para-la-prevencion-y-gestion-integral-de-residuos-solidos-de-los-municipios-de-la-jisoc\/?wpdmdl=2862&refresh=6a97eddc63dbf1788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/programa-intermunicipal-para-la-prevencion-y-gestion-integral-de-residuos-solidos-de-la-jicosur\/'>Programa Intermunicipal para la Prevenci\u00f3n y Gesti\u00f3n Integral de Residuos S\u00f3lidos de la JICOSUR<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 115.23 MB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/programa-intermunicipal-para-la-prevencion-y-gestion-integral-de-residuos-solidos-de-la-jicosur\/?wpdmdl=2860&refresh=6a97eddc6887c1788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/programa-municipal-para-la-prevencion-y-gestion-integral-de-residuos-guadalajara\/'>Programa Municipal para la Prevenci\u00f3n y Gesti\u00f3n Integral de Residuos Guadalajara<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 4.65 MB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/programa-municipal-para-la-prevencion-y-gestion-integral-de-residuos-guadalajara\/?wpdmdl=2852&refresh=6a97eddc6d1031788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/guia-para-elaboracion-de-programa-municipal-de-gestion-integral-de-residuos\/'>Gu\u00eda para elaboraci\u00f3n de Programa Municipal de Gesti\u00f3n Integral de Residuos<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 4.65 MB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/guia-para-elaboracion-de-programa-municipal-de-gestion-integral-de-residuos\/?wpdmdl=2811&refresh=6a97eddc718bd1788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/programa-intermunicipal-para-el-manejo-integral-de-residuos-solidos-sureste-2009-2016\/'>Programa Intermunicipal para el Manejo Integral de Residuos S\u00f3lidos Sureste 2009-2016<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 1.68 MB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/programa-intermunicipal-para-el-manejo-integral-de-residuos-solidos-sureste-2009-2016\/?wpdmdl=2813&refresh=6a97eddc75f871788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/programa-intermunicipal-para-la-prevencion-y-gestion-integral-de-residuos-solidos-y-de-manejo-especial-simar-altos-sur-2009-2012\/'>Programa Intermunicipal para la Prevenci\u00f3n y Gesti\u00f3n Integral de Residuos S\u00f3lidos y de Manejo Especial SIMAR Altos Sur 2009-2012<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 1.74 MB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/programa-intermunicipal-para-la-prevencion-y-gestion-integral-de-residuos-solidos-y-de-manejo-especial-simar-altos-sur-2009-2012\/?wpdmdl=2815&refresh=6a97eddc7a2e81788341724\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2817","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Programas y normas de residuos en Jalisco - Dra. Ma. Cristina Cortinas Dur\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cristinacortinas.org\/sustentabilidad\/programa-de-residuos-jalisco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programas y normas de residuos en Jalisco - Dra. Ma. Cristina Cortinas Dur\u00e1n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cristinacortinas.org\/sustentabilidad\/programa-de-residuos-jalisco\/\" \/>\n<meta property=\"og:site_name\" content=\"Dra. Ma. Cristina Cortinas Dur\u00e1n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cristinacortinasduran\/\" \/>\n<meta property=\"article:modified_time\" content=\"2017-06-21T20:05:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@DraCrisCortinas\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/programa-de-residuos-jalisco\\\/\",\"url\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/programa-de-residuos-jalisco\\\/\",\"name\":\"Programas y normas de residuos en Jalisco - Dra. Ma. Cristina Cortinas Dur\u00e1n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/#website\"},\"datePublished\":\"2016-03-29T06:51:55+00:00\",\"dateModified\":\"2017-06-21T20:05:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/programa-de-residuos-jalisco\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/programa-de-residuos-jalisco\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/programa-de-residuos-jalisco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programas y normas de residuos en Jalisco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/#website\",\"url\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/\",\"name\":\"Dra. Ma. Cristina Cortinas Dur\u00e1n\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programas y normas de residuos en Jalisco - Dra. Ma. Cristina Cortinas Dur\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cristinacortinas.org\/sustentabilidad\/programa-de-residuos-jalisco\/","og_locale":"es_ES","og_type":"article","og_title":"Programas y normas de residuos en Jalisco - Dra. Ma. Cristina Cortinas Dur\u00e1n","og_url":"https:\/\/cristinacortinas.org\/sustentabilidad\/programa-de-residuos-jalisco\/","og_site_name":"Dra. Ma. Cristina Cortinas Dur\u00e1n","article_publisher":"https:\/\/www.facebook.com\/cristinacortinasduran\/","article_modified_time":"2017-06-21T20:05:38+00:00","twitter_card":"summary_large_image","twitter_site":"@DraCrisCortinas","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cristinacortinas.org\/sustentabilidad\/programa-de-residuos-jalisco\/","url":"https:\/\/cristinacortinas.org\/sustentabilidad\/programa-de-residuos-jalisco\/","name":"Programas y normas de residuos en Jalisco - Dra. Ma. Cristina Cortinas Dur\u00e1n","isPartOf":{"@id":"https:\/\/cristinacortinas.org\/sustentabilidad\/#website"},"datePublished":"2016-03-29T06:51:55+00:00","dateModified":"2017-06-21T20:05:38+00:00","breadcrumb":{"@id":"https:\/\/cristinacortinas.org\/sustentabilidad\/programa-de-residuos-jalisco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cristinacortinas.org\/sustentabilidad\/programa-de-residuos-jalisco\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cristinacortinas.org\/sustentabilidad\/programa-de-residuos-jalisco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cristinacortinas.org\/sustentabilidad\/"},{"@type":"ListItem","position":2,"name":"Programas y normas de residuos en Jalisco"}]},{"@type":"WebSite","@id":"https:\/\/cristinacortinas.org\/sustentabilidad\/#website","url":"https:\/\/cristinacortinas.org\/sustentabilidad\/","name":"Dra. Ma. Cristina Cortinas Dur\u00e1n","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cristinacortinas.org\/sustentabilidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/cristinacortinas.org\/sustentabilidad\/wp-json\/wp\/v2\/pages\/2817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cristinacortinas.org\/sustentabilidad\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cristinacortinas.org\/sustentabilidad\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cristinacortinas.org\/sustentabilidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cristinacortinas.org\/sustentabilidad\/wp-json\/wp\/v2\/comments?post=2817"}],"version-history":[{"count":11,"href":"https:\/\/cristinacortinas.org\/sustentabilidad\/wp-json\/wp\/v2\/pages\/2817\/revisions"}],"predecessor-version":[{"id":4351,"href":"https:\/\/cristinacortinas.org\/sustentabilidad\/wp-json\/wp\/v2\/pages\/2817\/revisions\/4351"}],"wp:attachment":[{"href":"https:\/\/cristinacortinas.org\/sustentabilidad\/wp-json\/wp\/v2\/media?parent=2817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}