{"id":2166,"date":"2016-02-18T02:40:17","date_gmt":"2016-02-18T08:40:17","guid":{"rendered":"http:\/\/cristinacortinas.org\/sustentabilidad\/?page_id=2166"},"modified":"2016-04-09T10:34:17","modified_gmt":"2016-04-09T15:34:17","slug":"normatividad-de-salud-ambiental","status":"publish","type":"page","link":"https:\/\/cristinacortinas.org\/sustentabilidad\/normatividad-de-salud-ambiental\/","title":{"rendered":"Normatividad Nacional"},"content":{"rendered":"<div class=\"span12 \"><div class=\"title-box clearfix \"><h2 class=\"title-box_primary\">descargas<\/h2><\/div><!-- \/\/.title-box --><\/div>\n<hr \/>\n<div class=\"span7 \"><div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/convenio-de-diversidad-biologica\/'>Convenio de Diversidad Biol\u00f3gica<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 128.62 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/convenio-de-diversidad-biologica\/?wpdmdl=3004&refresh=6a98962f0edb91788384815\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pptx.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/ley-federal-de-responsabilidad-ambiental-y-los-riesgos-toxicos\/'>Ley Federal de Responsabilidad Ambiental y los Riesgos T\u00f3xicos<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 184.82 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/ley-federal-de-responsabilidad-ambiental-y-los-riesgos-toxicos\/?wpdmdl=2614&refresh=6a98962f13b871788384815\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<hr \/>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\"   src=\"http:\/\/cristinacortinas.org\/sustentabilidad\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/docx.png\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/cristinacortinas.org\/sustentabilidad\/download\/ley-federal-de-responsabilidad-ambiental\/'>Ley Federal de Responsabilidad Ambiental<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 118.00 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-info ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/cristinacortinas.org\/sustentabilidad\/download\/ley-federal-de-responsabilidad-ambiental\/?wpdmdl=2616&refresh=6a98962f180ea1788384815\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2166","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Normatividad Nacional - Dra. Ma. Cristina Cortinas Dur\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cristinacortinas.org\/sustentabilidad\/normatividad-de-salud-ambiental\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Normatividad Nacional - Dra. Ma. Cristina Cortinas Dur\u00e1n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cristinacortinas.org\/sustentabilidad\/normatividad-de-salud-ambiental\/\" \/>\n<meta property=\"og:site_name\" content=\"Dra. Ma. Cristina Cortinas Dur\u00e1n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cristinacortinasduran\/\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-09T15:34:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@DraCrisCortinas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/normatividad-de-salud-ambiental\\\/\",\"url\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/normatividad-de-salud-ambiental\\\/\",\"name\":\"Normatividad Nacional - Dra. Ma. Cristina Cortinas Dur\u00e1n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/#website\"},\"datePublished\":\"2016-02-18T08:40:17+00:00\",\"dateModified\":\"2016-04-09T15:34:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/normatividad-de-salud-ambiental\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/normatividad-de-salud-ambiental\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/normatividad-de-salud-ambiental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Normatividad Nacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/#website\",\"url\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/\",\"name\":\"Dra. Ma. Cristina Cortinas Dur\u00e1n\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cristinacortinas.org\\\/sustentabilidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Normatividad Nacional - Dra. Ma. Cristina Cortinas Dur\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cristinacortinas.org\/sustentabilidad\/normatividad-de-salud-ambiental\/","og_locale":"es_ES","og_type":"article","og_title":"Normatividad Nacional - Dra. Ma. Cristina Cortinas Dur\u00e1n","og_url":"https:\/\/cristinacortinas.org\/sustentabilidad\/normatividad-de-salud-ambiental\/","og_site_name":"Dra. Ma. Cristina Cortinas Dur\u00e1n","article_publisher":"https:\/\/www.facebook.com\/cristinacortinasduran\/","article_modified_time":"2016-04-09T15:34:17+00:00","twitter_card":"summary_large_image","twitter_site":"@DraCrisCortinas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cristinacortinas.org\/sustentabilidad\/normatividad-de-salud-ambiental\/","url":"https:\/\/cristinacortinas.org\/sustentabilidad\/normatividad-de-salud-ambiental\/","name":"Normatividad Nacional - Dra. Ma. Cristina Cortinas Dur\u00e1n","isPartOf":{"@id":"https:\/\/cristinacortinas.org\/sustentabilidad\/#website"},"datePublished":"2016-02-18T08:40:17+00:00","dateModified":"2016-04-09T15:34:17+00:00","breadcrumb":{"@id":"https:\/\/cristinacortinas.org\/sustentabilidad\/normatividad-de-salud-ambiental\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cristinacortinas.org\/sustentabilidad\/normatividad-de-salud-ambiental\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cristinacortinas.org\/sustentabilidad\/normatividad-de-salud-ambiental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cristinacortinas.org\/sustentabilidad\/"},{"@type":"ListItem","position":2,"name":"Normatividad Nacional"}]},{"@type":"WebSite","@id":"https:\/\/cristinacortinas.org\/sustentabilidad\/#website","url":"https:\/\/cristinacortinas.org\/sustentabilidad\/","name":"Dra. Ma. Cristina Cortinas Dur\u00e1n","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cristinacortinas.org\/sustentabilidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/cristinacortinas.org\/sustentabilidad\/wp-json\/wp\/v2\/pages\/2166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cristinacortinas.org\/sustentabilidad\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cristinacortinas.org\/sustentabilidad\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cristinacortinas.org\/sustentabilidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cristinacortinas.org\/sustentabilidad\/wp-json\/wp\/v2\/comments?post=2166"}],"version-history":[{"count":6,"href":"https:\/\/cristinacortinas.org\/sustentabilidad\/wp-json\/wp\/v2\/pages\/2166\/revisions"}],"predecessor-version":[{"id":3032,"href":"https:\/\/cristinacortinas.org\/sustentabilidad\/wp-json\/wp\/v2\/pages\/2166\/revisions\/3032"}],"wp:attachment":[{"href":"https:\/\/cristinacortinas.org\/sustentabilidad\/wp-json\/wp\/v2\/media?parent=2166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}